{"id":9333,"date":"2026-06-16T07:36:42","date_gmt":"2026-06-16T07:36:42","guid":{"rendered":"https:\/\/s-shaper.com\/application\/seamless-bodysuit\/"},"modified":"2026-06-25T06:04:26","modified_gmt":"2026-06-25T06:04:26","slug":"seamless-bodysuit","status":"publish","type":"application","link":"https:\/\/s-shaper.com\/es\/application\/seamless-bodysuit\/","title":{"rendered":"Body sin costuras"},"featured_media":9321,"parent":0,"template":"","meta":{"_acf_changed":false},"application-category":[71],"class_list":["post-9333","application","type-application","status-publish","has-post-thumbnail","hentry","application-category-core-essentials"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/s-shaper.com\/es\/wp-json\/wp\/v2\/application\/9333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/s-shaper.com\/es\/wp-json\/wp\/v2\/application"}],"about":[{"href":"https:\/\/s-shaper.com\/es\/wp-json\/wp\/v2\/types\/application"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/s-shaper.com\/es\/wp-json\/wp\/v2\/media\/9321"}],"wp:attachment":[{"href":"https:\/\/s-shaper.com\/es\/wp-json\/wp\/v2\/media?parent=9333"}],"wp:term":[{"taxonomy":"application-category","embeddable":true,"href":"https:\/\/s-shaper.com\/es\/wp-json\/wp\/v2\/application-category?post=9333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}