{"id":6222,"date":"2025-04-23T06:24:29","date_gmt":"2025-04-23T06:24:29","guid":{"rendered":"https:\/\/s-shaper.com\/?page_id=6222"},"modified":"2025-05-23T03:09:51","modified_gmt":"2025-05-23T03:09:51","slug":"technology-innovation","status":"publish","type":"page","link":"https:\/\/s-shaper.com\/de\/technology-innovation\/","title":{"rendered":"Technologie &amp; Innovation"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6222\" class=\"elementor elementor-6222\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2327f4 e-flex e-con-boxed e-con e-parent\" data-id=\"c2327f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38c4070 elementor-widget elementor-widget-heading\" data-id=\"38c4070\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Technologie und Innovation<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8db3f60 e-flex e-con-boxed e-con e-parent\" data-id=\"8db3f60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3d5d92f e-con-full e-flex e-con e-child\" data-id=\"3d5d92f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8623666 elementor-widget elementor-widget-image\" data-id=\"8623666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"405\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/RD-01.jpg\" class=\"attachment-large size-large wp-image-6225\" alt=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/RD-01.jpg 800w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/RD-01-300x152.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/RD-01-768x389.jpg 768w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/RD-01-18x9.jpg 18w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/RD-01-600x304.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8c2962 e-con-full e-flex e-con e-child\" data-id=\"a8c2962\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-125ec16 elementor-widget elementor-widget-heading\" data-id=\"125ec16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pionierarbeit f\u00fcr die Zukunft der Shapewear mit Spitzentechnologie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f606fb7 elementor-widget elementor-widget-text-editor\" data-id=\"f606fb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bei S-SHAPER glauben, dass Innovation der Schl\u00fcssel zum Erfolg ist. Unser engagiertes F&amp;E-Team und unsere fortschrittlichen Fertigungsverfahren erm\u00f6glichen es uns, leistungsstarke Shapewear-L\u00f6sungen zu entwickeln, die Komfort, Funktion und \u00c4sthetik vereinen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a770472 e-grid e-con-full e-con e-child\" data-id=\"a770472\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4c6710 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c4c6710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M597.333333 64V938.666667h-85.333333V158.037333L320 209.493333V121.130667l213.333333-57.130667H597.333333z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t3D Body Mapping f\u00fcr pr\u00e4zise Passform\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMa\u00dfgeschneiderte Designs auf der Grundlage realer menschlicher K\u00f6rperdaten\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4880a9 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d4880a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M682.666667 320a170.666667 170.666667 0 0 0-341.333334 0H256a256 256 0 1 1 454.954667 161.109333l-312.32 372.181334L768 853.333333v85.333334H256v-48.085334l386.730667-460.885333c25.856-30.72 40.021333-69.546667 39.936-109.696z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNahtlos gestrickte Technologie\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBeseitigt unbequeme N\u00e4hte f\u00fcr ein Gef\u00fchl wie auf der zweiten Haut\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd38ac elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6fd38ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M768 85.333333v58.112L546.517333 407.466667a277.376 277.376 0 1 1-303.616 342.528l82.773334-20.736A192.085333 192.085333 0 0 0 704 682.666667a192 192 0 0 0-277.546667-171.946667l-9.728 5.205333-29.44-51.498666L633.813333 170.666667H277.333333V85.333333H768z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIntelligente Kompressionszonen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAdaptive Formgebung zur Betonung der Kurven bei gleichzeitiger Gew\u00e4hrleistung des Komforts\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7252186 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7252186\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M682.666667 64V682.666667h128v85.333333h-128v170.666667h-85.333334v-170.666667H170.666667v-47.018667L597.333333 64h85.333334zM597.333333 682.666667V220.629333L297.301333 682.666667H597.333333z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAtmungsaktive, feuchtigkeitsableitende Stoffe\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tModerne Materialien f\u00fcr ganzt\u00e4gigen Tragekomfort\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8082bb3 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8082bb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M768 85.333333v85.333334H396.8l-28.885333 274.986666a277.333333 277.333333 0 1 1-125.013334 304.341334l82.773334-20.736A192.085333 192.085333 0 0 0 704 682.666667a192 192 0 0 0-192-192c-86.272 0-139.861333 27.264-168.96 65.28l-67.2-50.432L320 85.333333H768z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNachhaltige Textilinnovation\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUmweltfreundliche Produktion mit minimalem Abfall\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74edc92 elementor-widget elementor-widget-button\" data-id=\"74edc92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/s-shaper.com\/de\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">KONTAKT \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d40b07c e-flex e-con-boxed e-con e-parent\" data-id=\"d40b07c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa26924 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"aa26924\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"178415908\" aria-label=\"Registerkarten. \u00d6ffnen Sie Elemente mit Eingabe oder Leertaste, schlie\u00dfen Sie sie mit Escape und navigieren Sie mit den Pfeiltasten.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1784159081\" data-tab-title-id=\"e-n-tab-title-1784159081\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1784159081\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M597.333333 64V938.666667h-85.333333V158.037333L320 209.493333V121.130667l213.333333-57.130667H597.333333z\"><\/path><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M597.333333 64V938.666667h-85.333333V158.037333L320 209.493333V121.130667l213.333333-57.130667H597.333333z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t3D-K\u00f6rpermapping &amp; Pr\u00e4zisionspassform\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1784159082\" data-tab-title-id=\"e-n-tab-title-1784159082\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1784159082\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M682.666667 320a170.666667 170.666667 0 0 0-341.333334 0H256a256 256 0 1 1 454.954667 161.109333l-312.32 372.181334L768 853.333333v85.333334H256v-48.085334l386.730667-460.885333c25.856-30.72 40.021333-69.546667 39.936-109.696z\"><\/path><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M682.666667 320a170.666667 170.666667 0 0 0-341.333334 0H256a256 256 0 1 1 454.954667 161.109333l-312.32 372.181334L768 853.333333v85.333334H256v-48.085334l386.730667-460.885333c25.856-30.72 40.021333-69.546667 39.936-109.696z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tNahtlos gestrickte Technologie\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1784159083\" data-tab-title-id=\"e-n-tab-title-1784159083\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1784159083\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M768 85.333333v58.112L546.517333 407.466667a277.376 277.376 0 1 1-303.616 342.528l82.773334-20.736A192.085333 192.085333 0 0 0 704 682.666667a192 192 0 0 0-277.546667-171.946667l-9.728 5.205333-29.44-51.498666L633.813333 170.666667H277.333333V85.333333H768z\"><\/path><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M768 85.333333v58.112L546.517333 407.466667a277.376 277.376 0 1 1-303.616 342.528l82.773334-20.736A192.085333 192.085333 0 0 0 704 682.666667a192 192 0 0 0-277.546667-171.946667l-9.728 5.205333-29.44-51.498666L633.813333 170.666667H277.333333V85.333333H768z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tIntelligente Kompressionstechnologie\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1784159084\" data-tab-title-id=\"e-n-tab-title-1784159084\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1784159084\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M682.666667 64V682.666667h128v85.333333h-128v170.666667h-85.333334v-170.666667H170.666667v-47.018667L597.333333 64h85.333334zM597.333333 682.666667V220.629333L297.301333 682.666667H597.333333z\"><\/path><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M682.666667 64V682.666667h128v85.333333h-128v170.666667h-85.333334v-170.666667H170.666667v-47.018667L597.333333 64h85.333334zM597.333333 682.666667V220.629333L297.301333 682.666667H597.333333z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tFortschrittliche Gewebetechnologie\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1784159085\" data-tab-title-id=\"e-n-tab-title-1784159085\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1784159085\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M768 85.333333v85.333334H396.8l-28.885333 274.986666a277.333333 277.333333 0 1 1-125.013334 304.341334l82.773334-20.736A192.085333 192.085333 0 0 0 704 682.666667a192 192 0 0 0-192-192c-86.272 0-139.861333 27.264-168.96 65.28l-67.2-50.432L320 85.333333H768z\"><\/path><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewbox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M768 85.333333v85.333334H396.8l-28.885333 274.986666a277.333333 277.333333 0 1 1-125.013334 304.341334l82.773334-20.736A192.085333 192.085333 0 0 0 704 682.666667a192 192 0 0 0-192-192c-86.272 0-139.861333 27.264-168.96 65.28l-67.2-50.432L320 85.333333H768z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t Nachhaltige &amp; umweltfreundliche Herstellung\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1784159081\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1784159081\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-663ad63 e-con-full e-flex e-con e-child\" data-id=\"663ad63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38ef81e elementor-widget elementor-widget-heading\" data-id=\"38ef81e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Datengesteuertes Design f\u00fcr ultimativen Komfort und Unterst\u00fctzung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36c278d elementor-widget elementor-widget-text-editor\" data-id=\"36c278d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Traditionelle Shapewear folgt oft einem Ansatz nach dem Motto \u201eOne Size Fits All\u201c, was zu Passformproblemen und Unbehagen f\u00fchrt. Bei S-SHAPER verwenden wir 3D-K\u00f6rperscans und KI-gest\u00fctzte Musterentwicklung, um Shapewear zu kreieren, die wirklich passt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31425a7 elementor-widget elementor-widget-image\" data-id=\"31425a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"581\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/05\/3d-body.jpg\" class=\"attachment-large size-large wp-image-6379\" alt=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/05\/3d-body.jpg 1200w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/05\/3d-body-300x145.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/05\/3d-body-768x372.jpg 768w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/05\/3d-body-18x9.jpg 18w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/05\/3d-body-600x291.jpg 600w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/05\/3d-body-1000x484.jpg 1000w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f8456b e-flex e-con-boxed e-con e-child\" data-id=\"5f8456b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5acecc6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5acecc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udd39 So funktioniert es:<br \/>\u2714 3D-Scantechnologie \u2013 Sammelt Daten von \u00fcber 100.000 K\u00f6rperprofilen, um passgenaue Designs zu erstellen<br \/>\u2714 Adaptive Kompressionszonen \u2013 Gew\u00e4hrleistet gezielte Unterst\u00fctzung ohne \u00fcberm\u00e4\u00dfige Enge<br \/>\u2714 Ergonomische Musterentwicklung \u2013 Eliminiert Druckstellen f\u00fcr mehr Komfort<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd28f1 elementor-widget elementor-widget-text-editor\" data-id=\"fdd28f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udcca Ergebnisse:<br \/>\u2714 95 % Kundenzufriedenheit in Bezug auf die Passgenauigkeit<br \/>\u2714 30 % Reduzierung der Retouren aufgrund von Gr\u00f6\u00dfenproblemen<br \/>\u2714 Ma\u00dfgeschneiderte Shapewear-L\u00f6sungen f\u00fcr verschiedene K\u00f6rpertypen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1784159082\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1784159082\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-38057c5 e-con-full e-flex e-con e-child\" data-id=\"38057c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-569c42e elementor-widget elementor-widget-heading\" data-id=\"569c42e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Unsichtbarer Halt, maximaler Komfort<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d98fe76 elementor-widget elementor-widget-text-editor\" data-id=\"d98fe76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Traditionelle Shapewear hat oft sichtbare N\u00e4hte, klobige N\u00e4hte und unangenehme Druckstellen. Unsere nahtlose Stricktechnologie schafft elegante, ultra-glatte Shapewear, die sich auf nat\u00fcrliche Weise mit dem K\u00f6rper bewegt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd79fee elementor-widget elementor-widget-image\" data-id=\"fd79fee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"681\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/close_up_of_hands_image_.jpg\" class=\"attachment-large size-large wp-image-6057\" alt=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/close_up_of_hands_image_.jpg 900w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/close_up_of_hands_image_-300x227.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/close_up_of_hands_image_-768x581.jpg 768w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/close_up_of_hands_image_-16x12.jpg 16w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/close_up_of_hands_image_-600x454.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5a475e e-flex e-con-boxed e-con e-child\" data-id=\"d5a475e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1edfe46 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1edfe46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udd39 Hauptvorteile:<br \/>\u2705 Keine sichtbaren N\u00e4hte \u2013 Perfekt zum Tragen unter enger Kleidung<br \/>\u2705 Erh\u00f6hte Haltbarkeit \u2013 Nahtlose Konstruktion verhindert Rei\u00dfen und Ausfransen<br \/>\u2705 Ultra-Stretch-Gewebe \u2013 Passt sich den K\u00f6rperbewegungen ohne Einschr\u00e4nkung an<br \/>\u2705 Leicht &amp; atmungsaktiv \u2013 Ideal f\u00fcr den ganzt\u00e4gigen Gebrauch<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-849a409 elementor-widget elementor-widget-text-editor\" data-id=\"849a409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Herausforderung: Ben\u00f6tigte einen hochkomprimierenden Body, der unter der Kleidung unsichtbar bleibt<br \/>L\u00f6sung: Entwickelte einen nahtlosen, hautengen Body mit adaptiver Kompression<br \/>Ergebnisse: Wurde zu einem Bestseller und steigerte den Umsatz in der Kategorie um 42 %<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1784159083\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1784159083\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-e292590 e-con-full e-flex e-con e-child\" data-id=\"e292590\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c335f9b elementor-widget elementor-widget-heading\" data-id=\"c335f9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gezieltes Formen ohne Beschwerden<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24c31e0 elementor-widget elementor-widget-text-editor\" data-id=\"24c31e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kompression ist der Schl\u00fcssel zu effektiver Shapewear, aber zu viel Druck kann zu Beschwerden f\u00fchren, w\u00e4hrend zu wenig keine Ergebnisse liefert. Unsere Smart Compression Technology erm\u00f6glicht eine pr\u00e4zise Steuerung der Formintensit\u00e4t und sorgt so f\u00fcr eine schmeichelhafte Silhouette ohne Beschwerden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff73cb9 elementor-widget elementor-widget-image\" data-id=\"ff73cb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"616\" height=\"493\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_group_of_profess_image_-1.jpg\" class=\"attachment-large size-large wp-image-6216\" alt=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_group_of_profess_image_-1.jpg 616w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_group_of_profess_image_-1-300x240.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_group_of_profess_image_-1-15x12.jpg 15w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_group_of_profess_image_-1-600x480.jpg 600w\" sizes=\"(max-width: 616px) 100vw, 616px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-014eb5e e-flex e-con-boxed e-con e-child\" data-id=\"014eb5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10eadb8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"10eadb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udd39 So erreichen wir das:<br \/>\u2714 Zonenkompressions-Mapping \u2013 H\u00f6here Kompression in Formbereichen, leichter in Komfortzonen<br \/>\u2714 Atmungsaktives, mehrschichtiges Weben \u2013 Gew\u00e4hrleistet festen Halt bei gleichzeitiger Aufrechterhaltung des Luftstroms<br \/>\u2714 Adaptiver Stretch \u2013 Dehnt und zieht sich mit den K\u00f6rperbewegungen zusammen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85aac52 elementor-widget elementor-widget-text-editor\" data-id=\"85aac52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udcca Ergebnisse:<br \/>\u2714 +28 % Steigerung der Kundenbindung durch verbesserten Komfort<br \/>\u2714 4,9\/5 durchschnittliche Kundenbewertung f\u00fcr Gef\u00fchl und Halt<br \/>\u2714 Reduzierte Roll- und Knitterprobleme, die bei traditioneller Shapewear \u00fcblich sind<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1784159084\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1784159084\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\"elementor-element elementor-element-74e26ae e-con-full e-flex e-con e-child\" data-id=\"74e26ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb3abed elementor-widget elementor-widget-heading\" data-id=\"cb3abed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hochleistungsmaterialien f\u00fcr verbesserte Tragbarkeit<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6c8c6d elementor-widget elementor-widget-text-editor\" data-id=\"d6c8c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir investieren in Textilien der n\u00e4chsten Generation, um den Komfort, die Haltbarkeit und die Funktionalit\u00e4t unserer Shapewear zu verbessern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fc4dc2 elementor-widget elementor-widget-image\" data-id=\"0fc4dc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"681\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_shapewear_qualit_image_.jpg\" class=\"attachment-large size-large wp-image-6120\" alt=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_shapewear_qualit_image_.jpg 900w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_shapewear_qualit_image_-300x227.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_shapewear_qualit_image_-768x581.jpg 768w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_shapewear_qualit_image_-16x12.jpg 16w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_shapewear_qualit_image_-600x454.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e6a0d elementor-widget elementor-widget-text-editor\" data-id=\"d8e6a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udd39 Unsere Stoffinnovationen umfassen:<br \/>\u2705 Feuchtigkeitsableitende Mikrofasern \u2013 H\u00e4lt die Haut trocken und k\u00fchl<br \/>\u2705 Antibakterielle &amp; hypoallergene Materialien \u2013 Ideal f\u00fcr<br \/>\u2705 4-Wege-Stretch-Lycra\u00ae-Mischungen \u2013 Maximale Flexibilit\u00e4t ohne Formverlust<br \/>\u2705 W\u00e4rmeaktivierte Stoffspeicherung \u2013 Passt sich der K\u00f6rpertemperatur an und sorgt f\u00fcr eine individuelle Formgebung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1784159085\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1784159085\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\"elementor-element elementor-element-6a74680 e-con-full e-flex e-con e-child\" data-id=\"6a74680\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56b58b0 elementor-widget elementor-widget-heading\" data-id=\"56b58b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Abfall reduzieren, Effizienz steigern<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cf92c4 elementor-widget elementor-widget-text-editor\" data-id=\"1cf92c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nachhaltigkeit ist in der Modeindustrie nicht mehr optional. Bei S-SHAPER setzen wir uns f\u00fcr eine umweltvertr\u00e4gliche Produktion ein, ohne Kompromisse bei der Qualit\u00e4t einzugehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5dd4e elementor-widget elementor-widget-image\" data-id=\"3b5dd4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"350\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_close_up_shot_of_image_-1.jpg\" class=\"attachment-large size-large wp-image-6179\" alt=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_close_up_shot_of_image_-1.jpg 600w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_close_up_shot_of_image_-1-300x175.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_close_up_shot_of_image_-1-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d08209e e-flex e-con-boxed e-con e-child\" data-id=\"d08209e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e23da81 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e23da81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83c\udf31 Unsere Nachhaltigkeitsinitiativen:<br \/>\u2714 100 % recycelte und biologisch abbaubare Stoffe \u2013 Reduzierung der Umweltbelastung<br \/>\u2714 Wasserfreies F\u00e4rbeverfahren \u2013 Reduzierung des Wasserverbrauchs um 70 %<br \/>\u2714 Solarbetriebene Produktionsst\u00e4tten \u2013 Reduzierung des CO2-Fu\u00dfabdrucks<br \/>\u2714 Zero-Waste-Schneidetechnologie \u2013 Maximierung der Stoffeffizienz<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fc3097 elementor-widget elementor-widget-text-editor\" data-id=\"8fc3097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udcca Ergebnisse:<br \/>\u2714 Zertifiziert von OEKO-TEX\u00ae &amp; GRS (Global Recycled Standard)<br \/>\u2714 50 % weniger Emissionen als bei herk\u00f6mmlichen Herstellungsverfahren<br \/>\u2714 Steigende Nachfrage von umweltbewussten Marken<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0b34ff e-flex e-con-boxed e-con e-parent\" data-id=\"c0b34ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0409da2 elementor-widget elementor-widget-heading\" data-id=\"0409da2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Innovationspfeiler<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e964bb e-grid e-con-full e-con e-child\" data-id=\"1e964bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2662c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7d2662c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/two_chinese_profes_image__1.jpg\" class=\"attachment-full size-full wp-image-6062\" alt=\"\" title=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/two_chinese_profes_image__1.jpg 600w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/two_chinese_profes_image__1-300x200.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/two_chinese_profes_image__1-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Human-Centered Design<\/h3><p class=\"elementor-image-box-description\">Produkte, die auf realen K\u00f6rperdaten basieren, nicht auf idealisierten Figuren.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d2e79d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8d2e79d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_worker_holds_a_s_image_.jpg\" class=\"attachment-full size-full wp-image-6059\" alt=\"\" title=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_worker_holds_a_s_image_.jpg 600w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_worker_holds_a_s_image_-300x200.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_worker_holds_a_s_image_-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Exzellenz in der Materialwissenschaft<\/h3><p class=\"elementor-image-box-description\">Zusammenarbeit mit f\u00fchrenden Textillabors zur Beschaffung und Pr\u00fcfung von Stoffen der n\u00e4chsten Generation.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed43be3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ed43be3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_clean_well_orga_image_.jpg\" class=\"attachment-full size-full wp-image-6061\" alt=\"\" title=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_clean_well_orga_image_.jpg 600w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_clean_well_orga_image_-300x200.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/a_clean_well_orga_image_-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Umweltbewusste Fertigung<\/h3><p class=\"elementor-image-box-description\">Wir setzen abfallarme Prozesse und ethische Beschaffungspraktiken ein und reduzieren so unseren \u00f6kologischen Fu\u00dfabdruck.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01b046c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"01b046c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/folded_and_package_image_.jpg\" class=\"attachment-full size-full wp-image-6068\" alt=\"\" title=\"\" srcset=\"https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/folded_and_package_image_.jpg 600w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/folded_and_package_image_-300x200.jpg 300w, https:\/\/s-shaper.com\/wp-content\/uploads\/2025\/04\/folded_and_package_image_-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Von echten Personen getragen und getestet<\/h3><p class=\"elementor-image-box-description\">Alle Produkte werden von Personen mit unterschiedlichen K\u00f6rpertypen getestet, um universellen Komfort und Leistung zu gew\u00e4hrleisten.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Technology &#038; Innovation Pioneering the Future of Shapewear with Cutting-Edge Technology At\u00a0S-SHAPER, we believe that\u00a0innovation drives success. Our dedicated\u00a0R&amp;D team and advanced manufacturing processes\u00a0allow us to develop\u00a0high-performance shapewear solutions\u00a0that combine\u00a0comfort, function, and aesthetic appeal. 3D Body Mapping for Precision Fit Tailored designs based on real human body data Seamless Knitting Technology Eliminates uncomfortable seams for [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6222","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"_links":{"self":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/pages\/6222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/comments?post=6222"}],"version-history":[{"count":38,"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/pages\/6222\/revisions"}],"predecessor-version":[{"id":6498,"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/pages\/6222\/revisions\/6498"}],"wp:attachment":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/media?parent=6222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}