{"id":9332,"date":"2026-06-16T07:36:42","date_gmt":"2026-06-16T07:36:42","guid":{"rendered":"https:\/\/s-shaper.com\/application\/seamless-thermal-underwear\/"},"modified":"2026-06-25T06:04:26","modified_gmt":"2026-06-25T06:04:26","slug":"seamless-thermal-underwear","status":"publish","type":"application","link":"https:\/\/s-shaper.com\/de\/application\/seamless-thermal-underwear\/","title":{"rendered":"Nahtlose Thermounterw\u00e4sche"},"featured_media":9283,"parent":0,"template":"","meta":{"_acf_changed":false},"application-category":[71],"class_list":["post-9332","application","type-application","status-publish","has-post-thumbnail","hentry","application-category-core-essentials"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/application\/9332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/application"}],"about":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/types\/application"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/media\/9283"}],"wp:attachment":[{"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/media?parent=9332"}],"wp:term":[{"taxonomy":"application-category","embeddable":true,"href":"https:\/\/s-shaper.com\/de\/wp-json\/wp\/v2\/application-category?post=9332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}